{"id":20384,"date":"2020-09-09T08:04:45","date_gmt":"2020-09-09T08:04:45","guid":{"rendered":"https:\/\/www.macmillaneducation.es\/iberia\/?page_id=20384"},"modified":"2020-11-24T11:35:05","modified_gmt":"2020-11-24T11:35:05","slug":"escape-game-virtual","status":"publish","type":"page","link":"https:\/\/www.macmillaneducation.es\/iberia\/la-rentree\/escape-game-virtual\/","title":{"rendered":"Escape Game VirtuEl"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20384\" class=\"elementor elementor-20384\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7dc1faa elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"7dc1faa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c4658bf\" data-id=\"c4658bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96c5dfd elementor-widget elementor-widget-spacer\" data-id=\"96c5dfd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff73f1c qode_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"ff73f1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7660fb5\" data-id=\"7660fb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5d4bc5 elementor-widget elementor-widget-text-editor\" data-id=\"a5d4bc5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<h2 style=\"text-align: center;\"><strong>R\u00e9ussirez-vous \u00e0 sauver Internet ? <\/strong><\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-213541e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"213541e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e48616c elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"e48616c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84c8a8f\" data-id=\"84c8a8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5ac310 elementor-widget elementor-widget-bridge_workflow\" data-id=\"e5ac310\" data-element_type=\"widget\" data-widget_type=\"bridge_workflow.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"qode-workflow \">\n            <span class=\"main-line\" style=\"background-color:#86318B;\"><\/span>\n            <div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#86318B;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n                    <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#86318B;background-color:#86318B;\"><\/span>\n                                            <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#86318B;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image right\">\n            <img width=\"400\" height=\"400\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_1.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_1.jpg 400w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_1-300x300.jpg 300w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_1-150x150.jpg 150w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_1-100x100.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#86318B;background-color:#86318B;\"><\/span>\n                            <h3>ESCAPE GAME VIRTUEL<\/h3>\n                                            <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#86318B;\"><\/span>\n    <div class=\"qode-workflow-item-inner reverse\">\n        <div class=\"qode-workflow-image left\">\n            <img width=\"400\" height=\"400\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_2.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_2.jpg 400w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_2-300x300.jpg 300w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_2-150x150.jpg 150w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/08\/escape_room_2-100x100.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#86318B;background-color:#86318B;\"><\/span>\n                                        <h6 class=\"qode-workflow-subtitle\"> Bad Tech, un d\u00e9veloppeur informatique diabolique, a diffus\u00e9 un virus qui se r\u00e9pand dans le monde entier et menace de d\u00e9truire non seulement tous les appareils \u00e9lectroniques de la plan\u00e8te mais aussi Internet tout entier !<\/h6>\n                                <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#86318B;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image left\">\n            <img width=\"678\" height=\"678\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_circulo_3.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_circulo_3.jpg 678w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_circulo_3-300x300.jpg 300w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_circulo_3-150x150.jpg 150w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_circulo_3-570x570.jpg 570w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_circulo_3-500x500.jpg 500w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_circulo_3-600x600.jpg 600w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_circulo_3-100x100.jpg 100w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#86318B;background-color:#86318B;\"><\/span>\n                                        <h6 class=\"qode-workflow-subtitle\">En vous aidant des indices, accomplissez diff\u00e9rentes missions pour sauver Internet ! <\/h6>\n                                <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#86318B;\"><\/span>\n    <div class=\"qode-workflow-item-inner reverse\">\n        <div class=\"qode-workflow-image right\">\n            <img width=\"1550\" height=\"958\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_frances.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_frances.jpg 1550w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_frances-300x185.jpg 300w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_frances-1024x633.jpg 1024w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_frances-768x475.jpg 768w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_frances-1536x949.jpg 1536w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_frances-700x433.jpg 700w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/09\/escape_frances-600x371.jpg 600w\" sizes=\"(max-width: 1550px) 100vw, 1550px\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#86318B;background-color:#86318B;\"><\/span>\n                                        <h6 class=\"qode-workflow-subtitle\">Tous les utilisateurs Macmillan ont un acc\u00e8s exclusif \u00e0 Advantage, l&#039;espace qui regroupe toutes les ressources au m\u00eame endroit et vous permet d&#039;y acc\u00e9der \u00e0 tout moment et depuis n\u2019importe quel dispositif.<\/h6>\n                                <\/div>\n    <\/div>\n<\/div>        <\/div>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-014b4aa elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"014b4aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd3f4ab\" data-id=\"bd3f4ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b6b3b3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6b6b3b3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/advantage.macmillan.es\/index.php\/teachers\/back_to_school\/type\/2812\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">ACC\u00c9DER<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b699b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"3b699b3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48d8cbb\" data-id=\"48d8cbb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b86f043 elementor-widget elementor-widget-spacer\" data-id=\"b86f043\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-770c613 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"770c613\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4758555\" data-id=\"4758555\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf58ebf elementor-widget elementor-widget-heading\" data-id=\"cf58ebf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Des ressources pour travailler les \u00e9motions et les r\u00e9lations sociales<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75873b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"75873b3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8617a53\" data-id=\"8617a53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55af5fb elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"55af5fb\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: rgba(134, 49, 139, 0.88)\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_5.png\" alt=\"Groupes de discussion\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Groupes de discussion<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><p>Un espace de discussion con\u00e7u pour que les grands adolescents puissent \u00e9changer avec d'autres apprenants et partager leurs exp\u00e9riences par rapport \u00e0 cette situation, tout en s'exprimant en fran\u00e7ais. Nous mettons \u00e0 leur disposition des packs de conversation afin de leur fournir les outils n\u00e9cessaires pour participer activement dans ces groupes.<\/p><p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/www.macmillaneducation.es\/iberia\/la-rentree\/groupes-de-discussion\/\"><span style=\"text-decoration: underline;\"><strong>ACC\u00c9DER<\/strong><\/span><\/a><\/span><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aa6b47a\" data-id=\"aa6b47a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afa84ab elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"afa84ab\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: rgba(134, 49, 139, 0.88)\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/boton_icono_8_2.png\" alt=\"Programme de formation en ligne\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Programme de formation en ligne<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><p>Notre programme de Rencontres virtuelles FLE est \u00e0 votre disposition pour vous aider avant, pendant et apr\u00e8s la rentr\u00e9e !<\/p><p style=\"text-align: center;\"><a href=\"https:\/\/www.macmillaneducation.es\/iberia\/la-rentree\/formation-en-ligne\/\"><span style=\"text-decoration: underline; color: #ffffff;\"><strong>ACC\u00c9DER<\/strong><\/span><\/a><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d45731a\" data-id=\"d45731a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08d5885 elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"08d5885\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: rgba(134, 49, 139, 0.88)\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_10.png\" alt=\"Des articles des c\u00e9l\u00e8bres magazines Mente y Cerebro, et Investigaci\u00f3n y Ciencia\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Des articles des c\u00e9l\u00e8bres magazines Mente y Cerebro, et Investigaci\u00f3n y Ciencia<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><p>Un choix d'articles des magazines appartenant \u00e0 notre groupe \u00e9ditorial pour vous tenir au courant des derni\u00e8res avanc\u00e9es scientifiques et psychologiques sur le COVID-19.<\/p><p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/www.macmillaneducation.es\/iberia\/la-rentree\/revues-scientifiques\/\"><span style=\"text-decoration: underline;\"><strong>ACC\u00c9DER<\/strong><\/span><\/a><\/span><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36b96ff elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"36b96ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83f6be7\" data-id=\"83f6be7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-651741a elementor-widget elementor-widget-spacer\" data-id=\"651741a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cfffd69 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"cfffd69\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6c0ccc3\" data-id=\"6c0ccc3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa6b041 elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"aa6b041\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: #449298\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_11.png\" alt=\"Tests de niveau\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Tests de niveau<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><p style=\"text-align: left;\">V\u00e9rifiez le niveau de vos apprenants apr\u00e8s la p\u00e9riode de confinement avec plusieurs sites qui proposent des tests de niveau.<\/p><p style=\"text-align: center;\"><a href=\"https:\/\/www.macmillaneducation.es\/iberia\/la-rentree\/tests-de-niveau\/\"><span style=\"color: #ffffff;\"><strong><span style=\"text-decoration: underline;\">ACC\u00c9DER<\/span><\/strong><\/span><\/a><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7511b76\" data-id=\"7511b76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f839cc4 elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"f839cc4\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_121.png\" alt=\"Ressources p\u00e9dagogiques\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Ressources p\u00e9dagogiques<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><h3 style=\"text-align: center;\"><span style=\"color: #ffffff; line-height: 1.1em; font-size: 30px;\">Ressources p\u00e9dagogiques<\/span><\/h3><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a07da85\" data-id=\"a07da85\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1f8bfd elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"b1f8bfd\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: #449298\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_12.png\" alt=\"Le coin r\u00e9vision\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Le coin r\u00e9vision<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><p style=\"text-align: center;\">Des activit\u00e9s pour r\u00e9viser et faire une mise au point destin\u00e9es aux apprenants du primaire, secondaire et bachillerato.<\/p><p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/www.macmillaneducation.es\/iberia\/la-rentree\/le-coin-revision\/\"><span style=\"text-decoration: underline;\"><strong>ACC\u00c9DER<\/strong><\/span><\/a><\/span><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3900d79 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"3900d79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db8b07e\" data-id=\"db8b07e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70be132 elementor-widget elementor-widget-spacer\" data-id=\"70be132\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>R\u00e9ussirez-vous \u00e0 sauver Internet ? ESCAPE GAME VIRTUEL Bad Tech, un d\u00e9veloppeur informatique diabolique, a diffus\u00e9 un virus qui se r\u00e9pand dans le monde entier et menace de d\u00e9truire non seulement tous les appareils \u00e9lectroniques de la plan\u00e8te mais aussi Internet tout entier ! En&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":19852,"menu_order":3,"comment_status":"open","ping_status":"closed","template":"full_width.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages\/20384"}],"collection":[{"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/comments?post=20384"}],"version-history":[{"count":20,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages\/20384\/revisions"}],"predecessor-version":[{"id":21140,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages\/20384\/revisions\/21140"}],"up":[{"embeddable":true,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages\/19852"}],"wp:attachment":[{"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/media?parent=20384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}