{"id":19948,"date":"2020-06-11T16:25:58","date_gmt":"2020-06-11T16:25:58","guid":{"rendered":"https:\/\/www.macmillaneducation.es\/iberia\/?page_id=19948"},"modified":"2020-09-15T13:49:31","modified_gmt":"2020-09-15T13:49:31","slug":"vuelta-a-clase-pmar","status":"publish","type":"page","link":"https:\/\/www.macmillaneducation.es\/iberia\/vuelta-a-clase-pmar\/","title":{"rendered":"VUELTA A CLASE PMAR"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19948\" class=\"elementor elementor-19948\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94198b8 qode_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"94198b8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-226e9da\" data-id=\"226e9da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b596b9 elementor-widget elementor-widget-text-editor\" data-id=\"7b596b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<h2 style=\"text-align: center;\">LA VUELTA A CLASE CON MACMILLAN PMAR<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dfb2f3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4dfb2f3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-191b642 elementor-widget elementor-widget-text-editor\" data-id=\"191b642\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<div>\n<h4 align=\"center\"><span lang=\"EN-US\">\nEn Macmillan somos conscientes del impacto que supondr\u00e1, en el inicio del pr\u00f3ximo curso, el cierre de las aulas que se ha producido este trimestre. Por esta raz\u00f3n, queremos ayudar al profesorado y alumnado ofreci\u00e9ndoles herramientas y recursos \u00fatiles para abordar el comienzo del curso 2020-21. <\/span><\/h4>\n<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-245dd3b elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"245dd3b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f07907\" data-id=\"3f07907\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b8431a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"9b8431a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"469\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/ordenador-1024x469.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/ordenador-1024x469.png 1024w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/ordenador-300x137.png 300w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/ordenador-768x352.png 768w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/ordenador-700x321.png 700w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/ordenador-600x275.png 600w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/ordenador.png 1150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-71e89cd\" data-id=\"71e89cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5b2144 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b5b2144\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<h4><strong>\u201cVuelta a clase con Macmillan\u201d<\/strong> es un programa que contempla soluciones para apoyaros, tanto a ti como a tus alumnos y alumnas, en el plano pedag\u00f3gico y en el plano emocional. Es un programa <strong>flexible<\/strong>, para que puedas adaptarlo a tus necesidades, y <strong>din\u00e1mico<\/strong> para responder a las circunstancias que est\u00e9n por venir.<\/h4>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1aabb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"a1aabb5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09c750c\" data-id=\"09c750c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e38084 elementor-widget elementor-widget-spacer\" data-id=\"8e38084\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a10965 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"8a10965\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7aab9e\" data-id=\"d7aab9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1af851 elementor-widget elementor-widget-heading\" data-id=\"d1af851\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recursos pedag\u00f3gicos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c1249c elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"0c1249c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-515d23d\" data-id=\"515d23d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-247924f elementor-widget elementor-widget-heading\" data-id=\"247924f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h4 style=\"background-color: rgb(255, 255, 255); letter-spacing: normal; text-align: center; text-transform: none; white-space: normal;\">Averigua el nivel con el que tus alumnos y alumnas\narrancan el curso y ay\u00fadales a ponerse al d\u00eda.<\/h4><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97a6080 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"97a6080\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dec0699\" data-id=\"dec0699\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50422c3 elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"50422c3\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: #449298\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_11.png\" alt=\"ACTIVIDADES DE DIAGN\u00d3STICO\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">ACTIVIDADES DE DIAGN\u00d3STICO<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><p style=\"text-align: center;\">Averigua el nivel con el que tus alumnos y alumnas arrancan el curso.\nTe proponemos actividades de diagn\u00f3stico para conocer el nivel de conocimientos que tienen de cada asignatura cursada el a\u00f1o anterior.\n<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\" https:\/\/www.macmillaneducation.es\/iberia\/vuelta-a-clase-pmar\/actividades-de-diagnostico_pmar\/\"><span style=\"text-decoration: underline;\"><strong>VER M\u00c1S<\/strong><\/span><\/a><\/span><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0105591\" data-id=\"0105591\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b32c27c elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"b32c27c\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_121.png\" alt=\"Recursos pedag\u00f3gicos\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Recursos pedag\u00f3gicos<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><h3 style=\"text-align: center;\"><span style=\"color: #ffffff; line-height: 1.1em; font-size: 30px;\">recursos pedag\u00f3gicos<\/span><\/h3><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9ee4ba5\" data-id=\"9ee4ba5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09122c4 elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"09122c4\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: #449298\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_12.png\" alt=\"Materiales de repaso\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Materiales de repaso<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\"><p style=\"text-align: center;\">Te proporcionamos res\u00famenes de contenidos de cada una de las actividades que has evaluado con las actividades de diagn\u00f3stico.<\/p>\n<p style=\"text-align: center;\">Tus alumnos y alumnas podr\u00e1n ponerse al d\u00eda r\u00e1pidamente repasando los contenidos de forma que puedan empezar el curso con el nivel adecuado.<\/p>\n<p style=\"text-align: center;\">Adem\u00e1s, te ofrecemos actividades previas, de refuerzo y ampliaci\u00f3n para atender la diversidad del aula.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\" https:\/\/www.macmillaneducation.es\/iberia\/vuelta-a-clase-pmar\/materiales-de-repaso-pmar\/\"><span style=\"text-decoration: underline;\"><strong>VER M\u00c1S<\/strong><\/span><\/a><\/span><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5f9a67 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"d5f9a67\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45b8bf9\" data-id=\"45b8bf9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bb5b5f elementor-widget elementor-widget-spacer\" data-id=\"6bb5b5f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18ae053 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"18ae053\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5a2358\" data-id=\"f5a2358\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8b12a4 elementor-widget elementor-widget-heading\" data-id=\"c8b12a4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RECURSOS PARA EL PLANO AFECTIVO Y SOCIAL<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec9c2c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"ec9c2c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97756d5\" data-id=\"97756d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f90909 elementor-widget elementor-widget-heading\" data-id=\"7f90909\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h4 style=\"background-color: rgb(255, 255, 255); letter-spacing: normal; text-align: center; text-transform: none; white-space: normal;\">Apoyo para que puedas ayudar a tus alumnos y alumnas a superar los efectos\nsociales y emocionales<br>de la crisis del Covid-19 mientras aprenden.<\/h4><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d5b402 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"1d5b402\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9f55fac\" data-id=\"9f55fac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6dd879 elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"c6dd879\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: rgba(134, 49, 139, 0.88)\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/escape_room.png\" alt=\"Escape room virtual\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Escape room virtual<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\">Tus alumnos necesitan respuestas a la situaci\u00f3n que estamos viviendo; \u00bfqu\u00e9 mejor forma que un Scape Room virtual para que hablen entre ellos y se informen sobre este tema a la vez que trabajan en equipo?\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\" https:\/\/www.macmillaneducation.es\/iberia\/vuelta-a-clase-pmar\/escape-room-virtual-pmar\/\"><span style=\"text-decoration: underline;\"><strong>VER M\u00c1S<\/strong><\/span><\/a><\/span><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2e4cbdc\" data-id=\"2e4cbdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fc11a9 elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"9fc11a9\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: rgba(134, 49, 139, 0.88)\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/06\/boton_icono_8_2.png\" alt=\"Formaci\u00f3n Online impartida por expertos\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">Formaci\u00f3n Online impartida por expertos<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\">Formaci\u00f3n creada e impartida por psic\u00f3logos y expertos en el tema, con el objetivo de proporcionarte herramientas pr\u00e1cticas que ayuden a los estudiantes con la vuelta a clase, para que puedan reconectar con sus compa\u00f1eros y compa\u00f1eras y gestionar su angustia emocional o duelo. \n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\" https:\/\/www.macmillaneducation.es\/iberia\/vuelta-a-clase-pmar\/formacion-online-pmar\/\"><span style=\"text-decoration: underline;\"><strong>VER M\u00c1S<\/strong><\/span><\/a><\/span><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-05cac29\" data-id=\"05cac29\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88154ba elementor-widget elementor-widget-bridge_image_with_text_over\" data-id=\"88154ba\" data-element_type=\"widget\" data-widget_type=\"bridge_image_with_text_over.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_image_with_text_over q_iwto_hover\"><div class=\"shader\" style = \"background-color: rgba(181, 11, 11, 0)\"><\/div><div class=\"shader_hover\" style=\"background-color: rgba(134, 49, 139, 0.88)\"><\/div><img itemprop=\"image\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/boton_icono_10.png\" alt=\"art\u00edculos exclusivos de prestigiosas revistas cient\u00edficas\" \/><div class=\"text\"><table><tr><td><h3 class=\"caption no_icon\" style=\"color: #FFFFFF;font-size: 30px;\">art\u00edculos exclusivos de prestigiosas revistas cient\u00edficas<\/h3><\/td><\/tr><\/table><table><tr><td><div class=\"desc\">Gracias al acuerdo con estas revistas de nuestro mismo grupo editorial, ponemos a tu disposici\u00f3n \u201cen exclusiva y en formato abierto\u201d, art\u00edculos cient\u00edficos y psicol\u00f3gicos para que puedas informarte de los \u00faltimos avances y opiniones de la comunidad cient\u00edfica sobre la crisis del COVID.\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\" https:\/\/www.macmillaneducation.es\/iberia\/vuelta-a-clase-pmar\/prensa-cientifica-pmar\/\"><span style=\"text-decoration: underline;\"><strong>VER M\u00c1S<\/strong><\/span><\/a><\/span><\/p><\/div><\/td><\/tr><\/table><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-639b05a elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"639b05a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1fb512\" data-id=\"c1fb512\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e2f0d1 elementor-widget elementor-widget-spacer\" data-id=\"2e2f0d1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d500759 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"d500759\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-441d153\" data-id=\"441d153\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-978742c elementor-widget elementor-widget-image\" data-id=\"978742c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/logo_360-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/logo_360-150x150.png 150w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/logo_360-300x300.png 300w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/logo_360-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a75bb66\" data-id=\"a75bb66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52116b6 elementor-widget elementor-widget-text-editor\" data-id=\"52116b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<h4>Adem\u00e1s, si necesitaras volver a ense\u00f1ar de forma remota en el futuro, cubriremos tus necesidades con el programa Macmillan 360: nuestra promesa de proporcionarte los recursos de ense\u00f1anza que necesitas para que tus clases online comiencen a funcionar r\u00e1pidamente. Ponte en contacto con tu representante de Macmillan para obtener m\u00e1s informaci\u00f3n.<\/h4>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4af4bf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"4af4bf8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e62507\" data-id=\"8e62507\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5eae64 elementor-widget elementor-widget-spacer\" data-id=\"e5eae64\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aac9a84 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"aac9a84\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1559ff8\" data-id=\"1559ff8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d9f6b8c elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"d9f6b8c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2b73a3c\" data-id=\"2b73a3c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a2036d elementor-widget elementor-widget-heading\" data-id=\"9a2036d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br><br><br><br> Contacta con tu representante Macmillan<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b32395 elementor-widget elementor-widget-text-editor\" data-id=\"1b32395\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<h4>Tu representante responder\u00e1 a las preguntas sobre este programa y sobre el resto de nuestro m\u00e9todos y recursos.\u00a0<\/h4>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2a0eae elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f2a0eae\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.macmillaneducation.es\/contacto\/formulario-de-reserva\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacta<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bb41faa\" data-id=\"bb41faa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bb9d4e elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3bb9d4e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"646\" src=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/ordenador_cita-1024x646.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/ordenador_cita-1024x646.png 1024w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/ordenador_cita-300x189.png 300w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/ordenador_cita-768x484.png 768w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/ordenador_cita-700x441.png 700w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/ordenador_cita-600x378.png 600w, https:\/\/www.macmillaneducation.es\/iberia\/wp-content\/uploads\/2020\/05\/ordenador_cita.png 1521w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5074d26 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"5074d26\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b689917\" data-id=\"b689917\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfa2fe5 elementor-widget elementor-widget-spacer\" data-id=\"cfa2fe5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LA VUELTA A CLASE CON MACMILLAN PMAR En Macmillan somos conscientes del impacto que supondr\u00e1, en el inicio del pr\u00f3ximo curso, el cierre de las aulas que se ha producido este trimestre. Por esta raz\u00f3n, queremos ayudar al profesorado y alumnado ofreci\u00e9ndoles herramientas y recursos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"open","ping_status":"closed","template":"full_width.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages\/19948"}],"collection":[{"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/comments?post=19948"}],"version-history":[{"count":19,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages\/19948\/revisions"}],"predecessor-version":[{"id":20560,"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/pages\/19948\/revisions\/20560"}],"wp:attachment":[{"href":"https:\/\/www.macmillaneducation.es\/iberia\/wp-json\/wp\/v2\/media?parent=19948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}